{"id":3082,"count":1,"description":"","link":"https:\/\/playguitar.com\/teachers\/genre\/electric-guitar-styles\/","name":"electric guitar styles","slug":"electric-guitar-styles","taxonomy":"teacher_genre","meta":[],"_links":{"self":[{"href":"https:\/\/playguitar.com\/teachers\/wp-json\/wp\/v2\/teacher_genre\/3082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/playguitar.com\/teachers\/wp-json\/wp\/v2\/teacher_genre"}],"about":[{"href":"https:\/\/playguitar.com\/teachers\/wp-json\/wp\/v2\/taxonomies\/teacher_genre"}],"wp:post_type":[{"href":"https:\/\/playguitar.com\/teachers\/wp-json\/wp\/v2\/teacher?teacher_genre=3082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}