{"id":1266,"count":1,"description":"","link":"https:\/\/playguitar.com\/teachers\/genre\/djent\/","name":"djent","slug":"djent","taxonomy":"teacher_genre","meta":[],"_links":{"self":[{"href":"https:\/\/playguitar.com\/teachers\/wp-json\/wp\/v2\/teacher_genre\/1266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/playguitar.com\/teachers\/wp-json\/wp\/v2\/teacher_genre"}],"about":[{"href":"https:\/\/playguitar.com\/teachers\/wp-json\/wp\/v2\/taxonomies\/teacher_genre"}],"wp:post_type":[{"href":"https:\/\/playguitar.com\/teachers\/wp-json\/wp\/v2\/teacher?teacher_genre=1266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}