{"id":3123,"count":12,"description":"","link":"https:\/\/playguitar.com\/teachers\/city\/huddersfield\/","name":"Huddersfield","slug":"huddersfield","taxonomy":"teacher_city","meta":[],"_links":{"self":[{"href":"https:\/\/playguitar.com\/teachers\/wp-json\/wp\/v2\/teacher_city\/3123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/playguitar.com\/teachers\/wp-json\/wp\/v2\/teacher_city"}],"about":[{"href":"https:\/\/playguitar.com\/teachers\/wp-json\/wp\/v2\/taxonomies\/teacher_city"}],"wp:post_type":[{"href":"https:\/\/playguitar.com\/teachers\/wp-json\/wp\/v2\/teacher?teacher_city=3123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}